{"id":868,"date":"2022-09-12T22:10:26","date_gmt":"2022-09-12T20:10:26","guid":{"rendered":"https:\/\/melancholia.fr\/melusine\/?p=868"},"modified":"2024-07-17T15:27:28","modified_gmt":"2024-07-17T13:27:28","slug":"p-2","status":"publish","type":"post","link":"https:\/\/melancholia.fr\/melusine\/2022\/09\/12\/p-2\/","title":{"rendered":"Chapitre 1, p. 2"},"content":{"rendered":"\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:44% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"604\" height=\"999\" src=\"https:\/\/i0.wp.com\/melancholia.fr\/melusine\/wp-content\/uploads\/2022\/09\/img135-1.jpg?resize=604%2C999&#038;ssl=1\" alt=\"\" class=\"wp-image-869 size-full\" srcset=\"https:\/\/i0.wp.com\/melancholia.fr\/melusine\/wp-content\/uploads\/2022\/09\/img135-1.jpg?resize=619%2C1024&amp;ssl=1 619w, https:\/\/i0.wp.com\/melancholia.fr\/melusine\/wp-content\/uploads\/2022\/09\/img135-1.jpg?resize=181%2C300&amp;ssl=1 181w, https:\/\/i0.wp.com\/melancholia.fr\/melusine\/wp-content\/uploads\/2022\/09\/img135-1.jpg?resize=768%2C1270&amp;ssl=1 768w, https:\/\/i0.wp.com\/melancholia.fr\/melusine\/wp-content\/uploads\/2022\/09\/img135-1.jpg?w=797&amp;ssl=1 797w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" data-recalc-dims=\"1\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>2 HISTOIRE<br>    L&#8217;avanture qui fit conno\u00eetre Pressi\u00ac<br>ne \u00e0 Elinas est particuliere. Ce Prince<br>apr\u00e9s la mort de sa femme s&#8217;\u00e9toit adon\u00ac<br>n\u00e9 \u00e0 la chasse comme \u00e0 un exercice af\u00ac<br>sez propre pour dissiper ses chagrins,<br>parce qu&#8217;on est toujours en action. Un<br>jour qu&#8217;il chassoit par une chaleur ex\u00ac<br>cessive, il se trouva separ\u00e9 de sa suite,<br>&amp; ayant grand soif, il s&#8217;avan\u00e7a vers<br>une fontaine o\u00f9 il entendit une Dame<br>qui chantoit parfaitement bien; il ap\u00ac<br>procha doucement, &amp; s&#8217;arr\u00eata quelque<br>tems pour l&#8217;\u00e9couter ; mais le desir de<br>la voir le pressant encore plus que la<br>soif , il marcha vers la fontaine, &amp; sa\u00ac<br>lua la Dame, qu&#8217;il trouva la plus belle<br>personne du monde.<br>    A peine eut-il achev\u00e9 son compli\u00ac<br>ment, sur l&#8217;heureuse rencontre qu&#8217;il<br>faisoit, &amp; receu celuy de la Dame,<br>qui luy avoit r\u00e9pondu fort galament,<br>qu&#8217;il vit arriver un Page tenant en<br>main un tres-beau cheval, &amp; le plus<br>richement harnach\u00e9 qu&#8217;il e\u00fbt jamais<br>v\u00fb. Ce Page dit \u00e0 Pressine , en l&#8217;a\u00ac<br>bordant: Madame , il est tems de<br>partir , si vous le trouvez \u00e0 propos;<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>2 HISTOIRE L&#8217;avanture qui fit conno\u00eetre Pressi\u00acne \u00e0 Elinas est particuliere. Ce Princeapr\u00e9s la mort de sa femme s&#8217;\u00e9toit adon\u00acn\u00e9 \u00e0 la chasse comme \u00e0 un exercice af\u00acsez propre pour dissiper ses chagrins,parce qu&#8217;on est toujours en action. Unjour qu&#8217;il chassoit par une chaleur ex\u00accessive, il se trouva separ\u00e9 de sa suite,&amp; ayant grand soif, &hellip; <a href=\"https:\/\/melancholia.fr\/melusine\/2022\/09\/12\/p-2\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Chapitre 1, p. 2<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,11],"tags":[],"class_list":["post-868","post","type-post","status-publish","format-standard","hentry","category-chapitre-1","category-histoire-de-melusine-edition-diplomatique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/posts\/868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/comments?post=868"}],"version-history":[{"count":4,"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/posts\/868\/revisions"}],"predecessor-version":[{"id":1247,"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/posts\/868\/revisions\/1247"}],"wp:attachment":[{"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/media?parent=868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/categories?post=868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/tags?post=868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}