{"id":1406,"date":"2024-07-20T17:12:19","date_gmt":"2024-07-20T15:12:19","guid":{"rendered":"https:\/\/melancholia.fr\/melusine\/?p=1406"},"modified":"2024-07-20T17:12:22","modified_gmt":"2024-07-20T15:12:22","slug":"chapitre-3-p-80","status":"publish","type":"post","link":"https:\/\/melancholia.fr\/melusine\/2024\/07\/20\/chapitre-3-p-80\/","title":{"rendered":"Chapitre 3, p. 80"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"604\" height=\"966\" src=\"https:\/\/i0.wp.com\/melancholia.fr\/melusine\/wp-content\/uploads\/2024\/07\/img535.jpg?resize=604%2C966&#038;ssl=1\" alt=\"\" class=\"wp-image-1407 size-full\" srcset=\"https:\/\/i0.wp.com\/melancholia.fr\/melusine\/wp-content\/uploads\/2024\/07\/img535.jpg?resize=640%2C1024&amp;ssl=1 640w, https:\/\/i0.wp.com\/melancholia.fr\/melusine\/wp-content\/uploads\/2024\/07\/img535.jpg?resize=188%2C300&amp;ssl=1 188w, https:\/\/i0.wp.com\/melancholia.fr\/melusine\/wp-content\/uploads\/2024\/07\/img535.jpg?resize=768%2C1229&amp;ssl=1 768w, https:\/\/i0.wp.com\/melancholia.fr\/melusine\/wp-content\/uploads\/2024\/07\/img535.jpg?w=820&amp;ssl=1 820w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" data-recalc-dims=\"1\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>80<br>HISTOIRE<br>les Terres de Josselin \u00e0 Alain son<br>frere le cadet, tous deux fils de son<br>oncle Alain ; mais je trouve ailleurs<br>qu&#8217;il garda ces grandes Terres pour<br>ses enfans , &amp; cela me paro\u00eet plus<br>vrai-semblable , puis qu&#8217;une des pre\u00ac<br>mieres raisons que Melusine luy all\u00e9\u00ac<br>gua pour luy faire entreprendre le<br>voyage de Bretagne, fut celle de re\u00ac<br>couvrer les grands biens que son pere<br>avoit laissez en ce pays-l\u00e0.<br>Quand Raimondin eut termin\u00e9 tou\u00ac<br>tes ses affaires , &amp; rendu hommage \u00e0<br>Thierry de ses Fiefs , ce Prince le re\u00ac<br>tint plusieurs jours aupr\u00e9s de lui pour<br>le r\u00e9jo\u00fcir, &amp; luy faire oublier ses tra\u00ac<br>vaux. Il mangea toujours seul avec<br>luy ; &amp; comme le Duc aimoit extr\u00e9\u00ac<br>mement la chasse , il luy en donna<br>le divertissement de toute maniere.<br>Au milieu de tant d&#8217;honneurs , &amp;<br>de plaisirs, Raimondin br\u00fbloit d&#8217;en\u00ac<br>vie de revoir sa chere Melusine; de<br>sorte qu&#8217;il prit cong\u00e9 du Duc; &amp; le<br>vieux Chevalier abordant le Prince,<br>luy presenta de la part de sa Ma\u00eetresse<br>un gobelet d&#8217;or enrichi de diamans. Il<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>80HISTOIREles Terres de Josselin \u00e0 Alain sonfrere le cadet, tous deux fils de sononcle Alain ; mais je trouve ailleursqu&#8217;il garda ces grandes Terres pourses enfans , &amp; cela me paro\u00eet plusvrai-semblable , puis qu&#8217;une des pre\u00acmieres raisons que Melusine luy all\u00e9\u00acgua pour luy faire entreprendre levoyage de Bretagne, fut celle de re\u00accouvrer les grands &hellip; <a href=\"https:\/\/melancholia.fr\/melusine\/2024\/07\/20\/chapitre-3-p-80\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Chapitre 3, p. 80<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,11],"tags":[],"class_list":["post-1406","post","type-post","status-publish","format-standard","hentry","category-chapitre-3","category-histoire-de-melusine-edition-diplomatique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/posts\/1406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/comments?post=1406"}],"version-history":[{"count":1,"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/posts\/1406\/revisions"}],"predecessor-version":[{"id":1408,"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/posts\/1406\/revisions\/1408"}],"wp:attachment":[{"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/media?parent=1406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/categories?post=1406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/melancholia.fr\/melusine\/wp-json\/wp\/v2\/tags?post=1406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}