{"id":216,"date":"2023-09-08T22:33:59","date_gmt":"2023-09-08T20:33:59","guid":{"rendered":"https:\/\/melancholia.fr\/astree\/wordpress\/?post_type=glossary&#038;p=216"},"modified":"2023-09-08T22:34:27","modified_gmt":"2023-09-08T20:34:27","slug":"cleontine","status":"publish","type":"glossary","link":"https:\/\/melancholia.fr\/astree\/wordpress\/glossary\/cleontine\/","title":{"rendered":"Cl\u00e9ontine"},"content":{"rendered":"<p style=\"text-align: justify;\">Druidesse du Forez. Parente du berger <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Damon&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Dans la premi&egrave;re partie: Berger du Lignon. Parent de la m&egrave;re de L&eacute;onide et de Cl&eacute;ontine. Amoureux de Fortune. Se tue quand il se croit trahi, &agrave; cause de sortil&egrave;ges de Mandrague amoureuse de lui. Histoire racont&eacute;e par Adamas (I, 11)&amp;lt;br\/&amp;gt;Attention: il existe un autre Damon, personnage essentiel, chevalier, amoureux de Madonte&amp;lt;br\/&amp;gt;&lt;\/div&gt;\"  href=\"https:\/\/melancholia.fr\/astree\/wordpress\/glossary\/damon\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'>Damon<\/a> (&laquo;&nbsp;non point trop esloign&eacute; parent de la vieille <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Cl&eacute;ontine&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Druidesse du Forez. Parente du berger Damon (&amp;quot;non point trop esloign&eacute; parent de la vieille Cl&eacute;ontine&amp;quot;) et de la m&egrave;re de L&eacute;onide. Rend un oracle &agrave; Bellinde apr&egrave;s la mort de C&eacute;lion.&amp;lt;br\/&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/melancholia.fr\/astree\/wordpress\/glossary\/cleontine\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'>Cl&eacute;ontine<\/a>&nbsp;&raquo;) et de la m&egrave;re de <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;L&eacute;onide&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Nymphe d&amp;#039;Isoure, dame de compagnie de Galath&eacute;e. Blonde. Bavarde. Spirituel. S&amp;#039;apitoie facilement. Ni&egrave;ce d&amp;#039;Adamas. Parente de Cl&eacute;ontine, du berger Damon et de Ligdamon. Amoureuse de C&eacute;ladon, elle l&amp;#039;aide &agrave; s&amp;#039;enfuir du ch&acirc;teau et renonce &agrave; sa passion.&amp;lt;br\/&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/melancholia.fr\/astree\/wordpress\/glossary\/leonide\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'>L&eacute;onide<\/a>. Rend un oracle &agrave; <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Bellinde&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Berg&egrave;re du Lignon. Fille de Phil&eacute;mon. Amie d&amp;#039;Amaranthe. Recherch&eacute;e par Ergaste. M&egrave;re de Diane, et d&amp;#039;Ergaste le jeune. &amp;quot;sage Bellinde&amp;quot;. Femme de C&eacute;lion. &amp;quot;Druide&amp;quot; et &amp;quot;vestale&amp;quot; &agrave; &Eacute;vian apr&egrave;s son veuvage (I, 6). Son histoire est racont&eacute;e par C&eacute;ladon &agrave; Galath&eacute;e (I, 10)&amp;lt;br\/&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/melancholia.fr\/astree\/wordpress\/glossary\/bellinde\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'>Bellinde<\/a> apr&egrave;s la mort de <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;C&eacute;lion&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Berger du Lignon. Fr&egrave;re de Diamis. Ami d&amp;#039;Ergaste. Ami puis &eacute;poux de Bellinde. P&egrave;re de Diane et d&amp;#039;Ergaste le jeune. Est qualifi&eacute; de &amp;quot;sage C&eacute;lion&amp;quot;. Meurt rapidement apr&egrave;s son mariage. Diane est enfant posthume. (I, 11)&lt;\/div&gt;\" href=\"https:\/\/melancholia.fr\/astree\/wordpress\/glossary\/celion\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'>C&eacute;lion<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Druidesse du Forez. Parente du berger <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Damon&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Dans la premi&egrave;re partie: Berger du Lignon. Parent de la m&egrave;re de L&eacute;onide et de Cl&eacute;ontine. Amoureux de Fortune. Se tue quand il se croit trahi, &agrave; cause de sortil&egrave;ges de Mandrague amoureuse de lui. Histoire racont&eacute;e par Adamas (I, 11)&amp;lt;br\/&amp;gt;Attention: il existe un autre Damon, personnage essentiel, chevalier, amoureux de Madonte&amp;lt;br\/&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/melancholia.fr\/astree\/wordpress\/glossary\/damon\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'>Damon<\/a> (&laquo;&nbsp;non point trop esloign&eacute; parent de la vieille <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Cl&eacute;ontine&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Druidesse du Forez. Parente du berger Damon (&amp;quot;non point trop esloign&eacute; parent de la vieille Cl&eacute;ontine&amp;quot;) et de la m&egrave;re de L&eacute;onide. Rend un oracle &agrave; Bellinde apr&egrave;s la mort de C&eacute;lion.&amp;lt;br\/&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/melancholia.fr\/astree\/wordpress\/glossary\/cleontine\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'>Cl&eacute;ontine<\/a>&nbsp;&raquo;) et de la m&egrave;re de <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;L&eacute;onide&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Nymphe d&amp;#039;Isoure, dame de compagnie de Galath&eacute;e. Blonde. Bavarde. Spirituel. S&amp;#039;apitoie facilement. Ni&egrave;ce d&amp;#039;Adamas. Parente de Cl&eacute;ontine, du berger Damon et de Ligdamon. Amoureuse de C&eacute;ladon, elle l&amp;#039;aide &agrave; s&amp;#039;enfuir du ch&acirc;teau et renonce &agrave; sa passion.&amp;lt;br\/&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/melancholia.fr\/astree\/wordpress\/glossary\/leonide\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'>L&eacute;onide<\/a>. Rend un oracle &agrave; <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Bellinde&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Berg&egrave;re du Lignon. Fille de Phil&eacute;mon. Amie d&amp;#039;Amaranthe. Recherch&eacute;e par Ergaste. M&egrave;re de Diane, et d&amp;#039;Ergaste le jeune. &amp;quot;sage Bellinde&amp;quot;. Femme de C&eacute;lion. &amp;quot;Druide&amp;quot; et &amp;quot;vestale&amp;quot; &agrave; &Eacute;vian apr&egrave;s son veuvage (I, 6). Son histoire est racont&eacute;e par C&eacute;ladon &agrave; Galath&eacute;e (I, 10)&amp;lt;br\/&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/melancholia.fr\/astree\/wordpress\/glossary\/bellinde\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'>Bellinde<\/a> apr&egrave;s la mort de <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;C&eacute;lion&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Berger du Lignon. Fr&egrave;re de Diamis. Ami d&amp;#039;Ergaste. Ami puis &eacute;poux de Bellinde. P&egrave;re de Diane et d&amp;#039;Ergaste le jeune. Est qualifi&eacute; de &amp;quot;sage C&eacute;lion&amp;quot;. Meurt rapidement apr&egrave;s son mariage. Diane est enfant posthume. (I, 11)&lt;\/div&gt;\" href=\"https:\/\/melancholia.fr\/astree\/wordpress\/glossary\/celion\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'>C&eacute;lion<\/a>.<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","meta":{"footnotes":""},"class_list":["post-216","glossary","type-glossary","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/melancholia.fr\/astree\/wordpress\/wp-json\/wp\/v2\/glossary\/216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/melancholia.fr\/astree\/wordpress\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/melancholia.fr\/astree\/wordpress\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/melancholia.fr\/astree\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/melancholia.fr\/astree\/wordpress\/wp-json\/wp\/v2\/glossary\/216\/revisions"}],"predecessor-version":[{"id":218,"href":"https:\/\/melancholia.fr\/astree\/wordpress\/wp-json\/wp\/v2\/glossary\/216\/revisions\/218"}],"wp:attachment":[{"href":"https:\/\/melancholia.fr\/astree\/wordpress\/wp-json\/wp\/v2\/media?parent=216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}